
{"id":47243,"date":"2025-08-06T10:55:47","date_gmt":"2025-08-06T09:55:47","guid":{"rendered":"https:\/\/movery.it\/?p=47243"},"modified":"2025-08-29T09:32:33","modified_gmt":"2025-08-29T08:32:33","slug":"snorkeling-al-parco-archeologico-sommerso-di-baia-9-e-16-agosto","status":"publish","type":"post","link":"https:\/\/movery.it\/fr\/snorkeling-al-parco-archeologico-sommerso-di-baia-9-e-16-agosto\/","title":{"rendered":"Plong\u00e9e en apn\u00e9e au parc arch\u00e9ologique sous-marin de Baia : 9 et 16 ao\u00fbt"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" >Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/movery.it\/fr\/snorkeling-al-parco-archeologico-sommerso-di-baia-9-e-16-agosto\/#Proposition_for_you\" title=\"Proposition pour vous\">Proposition pour vous<\/a><\/li><\/ul><\/nav><\/div>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"47243\" class=\"elementor elementor-47243\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68d35056 e-flex e-con-boxed e-con e-parent\" data-id=\"68d35056\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49438222 elementor-widget elementor-widget-text-editor\" data-id=\"49438222\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- wp:paragraph -->\n<p>B<strong>cour de ferme <\/strong>est l'une des zones arch\u00e9ologiques les plus belles et les plus spectaculaires de la Campanie. Situ\u00e9e dans la r\u00e9gion des Campi Flegrei, elle fait partie de la municipalit\u00e9 de <strong>Bacoli <\/strong>et aujourd'hui, on peut surtout admirer ce qui reste de la colline de la ville, alors qu'une grande partie repose sur le fond de la mer en raison de la pr\u00e9sence du <strong>bradys\u00e9isme <\/strong>qui caract\u00e9rise le territoire.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Aujourd'hui, Baia appartient officiellement \u00e0 la <strong>Parc arch\u00e9ologique de Campi Flegrei<\/strong>. Les principales d\u00e9couvertes arch\u00e9ologiques ont \u00e9t\u00e9 mises au jour gr\u00e2ce \u00e0 d'impressionnantes campagnes de fouilles qui ont d\u00e9but\u00e9 en 1941 et qui ont permis de d\u00e9couvrir des complexes thermaux, des villas et des b\u00e2timents datant de la fin de la p\u00e9riode r\u00e9publicaine et de l'\u00e9poque august\u00e9enne. Parmi les vestiges les plus fascinants d\u00e9couverts \u00e0 Baia, on peut citer les <strong>Temple de Diane<\/strong>les <strong>Temple de V\u00e9nus<\/strong> et le <strong>Temple de Mercure<\/strong>.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Une autre perle incontournable est le <strong>Parc submerg\u00e9 de Baia<\/strong>Le site est une zone marine prot\u00e9g\u00e9e \u00e9galement connue sous le nom de Pomp\u00e9i sous-marine, car sa structure urbaine est similaire \u00e0 celle de la ville ensevelie par le V\u00e9suve. Pourquoi ne pas vous offrir une journ\u00e9e fantastique de visite ?<strong> <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/baia-sommersa-il-parco-sottomarino-tra-archeologia-e-natura\/\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"broken_link\">plong\u00e9e en apn\u00e9e dans le parc arch\u00e9ologique sous-marin de Baia les 9 et 16 ao\u00fbt<\/a><\/strong>?<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph --><!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3200995 e-flex e-con-boxed e-con e-parent\" data-id=\"3200995\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9460967 elementor-widget elementor-widget-shortcode\" data-id=\"9460967\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    \n    <div class=\"st-relate st-hotel-room-content\">\n        <div class=\"relate-rooms\">\n            <div class=\"st-hr\"><\/div>\n            <h2 class=\"st-heading-section\"><span class=\"ez-toc-section\" id=\"Proposition_for_you\"><\/span>Proposition pour vous<span class=\"ez-toc-section-end\"><\/span><\/h2>\n            <div class=\"inner service-list-wrapper service-tour\">\n                <div class=\"owl-carousel st-owl-slider\" data-loop=\"false\" data-center=\"true\" data-margin=\"24\" data-responsive=\"{&quot;992&quot;:{&quot;items&quot;:4},&quot;768&quot;:{&quot;items&quot;:2},&quot;0&quot;:{&quot;items&quot;:1}}\"><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n        <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n            <div class=\"title\">\n                Excursions en kayak            <\/div>\n            <div class=\"icon\">\n\n                                    <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n\n                        <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n                            <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                            <div class=\"lds-dual-ring\"><\/div>\n                        <\/div>\n                    <\/a>\n                                <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperikayak-a-capo-miseno\/\">\n                    <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n                <\/a>\n                <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperikayak-a-capo-miseno\/\">\n                    <img decoding=\"async\" src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n                <\/a>\n\n            <\/div>\n\n        <\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                                <div class=\"feature_class st_featured_simple featured\"><div>- 5% di sconto per tour in kayak<\/div><\/div>                \n            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperikayak-a-capo-miseno\/\">\n                <img decoding=\"async\" class=\"feature_activity_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2024\/07\/kayak_mare_miseno_tour-scaled-450x300.jpg\" alt=\"Kayak &#038; SUP alba o tramonto sul mare di Capo Miseno (12 e 19 Luglio)\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n            <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperikayak-a-capo-miseno\/\" class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n                <p class=\"title\" itemprop=\"name\">\n                    Kayak &#038; SUP alba o tramonto sul mare di Capo Miseno (12 e 19 Luglio)                <\/p>\n            <\/a>\n            \n\n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Cap Miseno<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n                Vous voulez voir le littoral phl\u00e9gr\u00e9en sous un nouvel angle ? Achetez cette excursion en kayak d\u00e8s maintenant...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t4.7 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (7 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-07-15 13:27:51\">2026-07-15 13:27:51<\/div>\n\n                        <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\" >\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac30.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n\n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperikayak-a-capo-miseno\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n        <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n            <div class=\"title\">\n                Exp\u00e9rience en bateau            <\/div>\n            <div class=\"icon\">\n\n                                    <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n\n                        <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n                            <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                            <div class=\"lds-dual-ring\"><\/div>\n                        <\/div>\n                    <\/a>\n                                <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperi-cruise-serale-lungo-la-costa-flegrea\/\">\n                    <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n                <\/a>\n                <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperi-cruise-serale-lungo-la-costa-flegrea\/\">\n                    <img decoding=\"async\" src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n                <\/a>\n\n            <\/div>\n\n        <\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                                                \n            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperi-cruise-serale-lungo-la-costa-flegrea\/\">\n                <img decoding=\"async\" class=\"feature_activity_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2023\/06\/barca-e1689861732823-450x300.jpg\" alt=\"Aperi-cruise serale lungo la Costa Flegrea con partenza da Monte di Procida\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n            <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperi-cruise-serale-lungo-la-costa-flegrea\/\" class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n                <p class=\"title\" itemprop=\"name\">\n                    Aperi-cruise serale lungo la Costa Flegrea con partenza da Monte di Procida                <\/p>\n            <\/a>\n            \n\n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Port d'Acquamorta<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t3h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n                Vous souhaitez passer une soir\u00e9e inoubliable avec votre partenaire ou vos amis ? La croisi\u00e8re-ap\u00e9ritif le long de la...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t5 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (3 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-07-15 13:27:51\">2026-07-15 13:27:51<\/div>\n\n                        <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\" >\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac72.22<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n\n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/campania\/bacoli\/aperi-cruise-serale-lungo-la-costa-flegrea\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><\/div>            <\/div>\n        <\/div>\n    <\/div>\n    \n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02fada4 e-flex e-con-boxed e-con e-parent\" data-id=\"02fada4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9aee570 elementor-widget elementor-widget-text-editor\" data-id=\"9aee570\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>C'est l'exp\u00e9rience id\u00e9ale pour une famille ou des amis qui veulent profiter de l'arch\u00e9ologie et de la mer. En compagnie d'instructeurs et de guides agr\u00e9\u00e9s, vous pourrez nager entre les deux mers. <strong>ruines romaines<\/strong>, <strong>mosa\u00efques <\/strong>et <strong>statues <\/strong>Plongez \u00e0 quelques m\u00e8tres de profondeur et vivez un fantastique voyage dans le temps !<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Il y a 2000 ans, Baia \u00e9tait r\u00e9put\u00e9e pour ses thermes et son climat favorable, ce qui en faisait une destination privil\u00e9gi\u00e9e des aristocrates et des empereurs romains. \u00c0 partir du IVe si\u00e8cle apr\u00e8s J.-C., la ville de Baia est devenue un centre d'int\u00e9r\u00eat pour les aristocrates et les empereurs romains. <strong>lent naufrage<\/strong> ce qui a entra\u00een\u00e9 l'abandon des villas locales. Entre les ann\u00e9es 1960 et 1980, les premi\u00e8res statues et autres objets ont \u00e9t\u00e9 retrouv\u00e9s. <strong>Ch\u00e2teau de Baia<\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Cette journ\u00e9e de plong\u00e9e avec masque et tuba vous permettra d'admirer de pr\u00e8s des sites d'une rare beaut\u00e9 tels que <strong>Portus Iulius<\/strong>, <strong>Villa dei Pisoni<\/strong> et <strong>Villa \u00e0 Protiro<\/strong>. Pour chacun d'entre eux, il y aura un parcours sous-marin sp\u00e9cial pour observer ces tr\u00e9sors conserv\u00e9s au fond de la mer.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Baia est l'une des zones arch\u00e9ologiques les plus belles et les plus spectaculaires de Campanie. Situ\u00e9e dans la...<\/p>","protected":false},"author":10,"featured_media":28052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Giornata di snorkeling al Parco Archeologico Sommerso di Baia da vivere il 9 e 16 agosto","_seopress_titles_desc":"Vuoi vivere un\u2019esperienza unica e indimenticabile? Vieni con noi al Parco Archeologico Sommerso di Baia il 9 e 16 agosto per ammirare i tesori nascosti lungo il fondale marino","_seopress_robots_index":"","content-type":"","footnotes":""},"categories":[319],"tags":[],"locations":[193,167],"class_list":["post-47243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","locations-bacoli","locations-campania"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","_links":{"self":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/47243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/comments?post=47243"}],"version-history":[{"count":6,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/47243\/revisions"}],"predecessor-version":[{"id":47253,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/47243\/revisions\/47253"}],"wp:attachment":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/media?parent=47243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/categories?post=47243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/tags?post=47243"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/locations?post=47243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}