
{"id":58373,"date":"2026-03-30T08:00:00","date_gmt":"2026-03-30T07:00:00","guid":{"rendered":"https:\/\/movery.it\/?p=58373"},"modified":"2026-04-03T09:49:04","modified_gmt":"2026-04-03T08:49:04","slug":"come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni","status":"publish","type":"post","link":"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/","title":{"rendered":"Come trascorrere la Pasqua in Puglia tra tour, escursioni e degustazioni"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" >Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Le_migliori_esperienze_da_fare_in_Puglia_a_Pasqua\" title=\"Le migliori esperienze da fare in Puglia a Pasqua\">Le migliori esperienze da fare in Puglia a Pasqua<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Laboratori_di_cucina_e_cooking_class_in_provincia_di_Brindisi\" title=\"Laboratori di cucina e cooking class in provincia di Brindisi\">Laboratori di cucina e cooking class in provincia di Brindisi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Escursione_a_piedi_nel_cuore_di_Taranto\" title=\"Escursione a piedi nel cuore di Taranto\">Escursione a piedi nel cuore di Taranto<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Proposition_for_you\" title=\"Proposition pour vous\">Proposition pour vous<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Mozzarella_tour_a_Ostuni_con_degustazione_di_prodotti_locali\" title=\"Visite de la Mozzarella \u00e0 Ostuni avec d\u00e9gustation de produits locaux\">Visite de la Mozzarella \u00e0 Ostuni avec d\u00e9gustation de produits locaux<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Wine_tour_a_Monopoli_con_degustazione_di_prodotti_pugliesi\" title=\"Wine tour a Monopoli con degustazione di prodotti pugliesi\">Wine tour a Monopoli con degustazione di prodotti pugliesi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Corso_di_cucina_a_Polignano_a_Mare_con_degustazione_di_panzerotti_focacce_e_orecchiette\" title=\"Cours de cuisine \u00e0 Polignano a Mare avec d\u00e9gustation de panzerotti, focaccia et orecchiette\">Cours de cuisine \u00e0 Polignano a Mare avec d\u00e9gustation de panzerotti, focaccia et orecchiette<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Street_food_tour_a_Polignano_a_Mare_con_degustazione\" title=\"Visite guid\u00e9e de la cuisine de rue \u00e0 Polignano a Mare avec d\u00e9gustation\">Visite guid\u00e9e de la cuisine de rue \u00e0 Polignano a Mare avec d\u00e9gustation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Tour_privato_a_Polignano_Alberobello_e_Locorotondo_in_partenza_da_Matera\" title=\"Excursion priv\u00e9e \u00e0 Polignano, Alberobello et Locorotondo au d\u00e9part de Matera\">Excursion priv\u00e9e \u00e0 Polignano, Alberobello et Locorotondo au d\u00e9part de Matera<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Walking_tour_privato_a_Matera_in_partenza_da_Bari\" title=\"Excursion priv\u00e9e \u00e0 Matera au d\u00e9part de Bari\">Excursion priv\u00e9e \u00e0 Matera au d\u00e9part de Bari<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Tour_privato_nel_centro_storico_di_Ostuni\" title=\"Visite priv\u00e9e du centre historique d&#039;Ostuni\">Visite priv\u00e9e du centre historique d'Ostuni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Tour_privato_a_Bari_Gravina_Castel_del_Monte_e_Trani_in_partenza_da_Matera\" title=\"Tour privato a Bari, Gravina, Castel del Monte e Trani in partenza da Matera\">Tour privato a Bari, Gravina, Castel del Monte e Trani in partenza da Matera<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/movery.it\/fr\/come-trascorrere-la-pasqua-in-puglia-tra-tour-escursioni-e-degustazioni\/#Tour_guidato_tra_i_trulli_e_le_meraviglie_di_Alberobello\" title=\"Visite guid\u00e9e des trulli et des merveilles d&#039;Alberobello\">Visite guid\u00e9e des trulli et des merveilles d'Alberobello<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"58373\" class=\"elementor elementor-58373\">\n\t\t\t\t<div class=\"elementor-element elementor-element-767b35d3 e-flex e-con-boxed e-con e-parent\" data-id=\"767b35d3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52a83cd2 elementor-widget elementor-widget-text-editor\" data-id=\"52a83cd2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<!-- wp:paragraph -->\n<p>La <strong>Pasqua in Puglia<\/strong> \u00e8 una celebrazione profondamente radicata nelle tradizioni e nella cultura secolare della regione. Tra paesaggi mozzafiato, borghi ricchi di storia e una cucina dai sapori autentici, questa terra regala un\u2019esperienza davvero speciale durante le festivit\u00e0 pasquali. Dalle suggestive celebrazioni della<strong>Semaine Sainte<\/strong> fino alle usanze gastronomiche, ogni elemento contribuisce a rendere unica la Pasqua pugliese.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Se ti stai chiedendo cosa fare in Puglia a Pasqua, le possibilit\u00e0 sono numerose. Accanto ai riti religiosi, non mancano attivit\u00e0 capaci di arricchire il soggiorno e offrire uno sguardo pi\u00f9 completo sulla regione.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Tra gli eventi pi\u00f9 affascinanti spiccano senza dubbio le <strong>processioni<\/strong>, che rappresentano il cuore delle celebrazioni pasquali. Ogni citt\u00e0 custodisce le proprie tradizioni: ad <strong>Andria<\/strong>, ad esempio, la processione del Venerd\u00ec Santo colpisce per la sua intensit\u00e0, con statue lignee portate in spalla dai fedeli; a <strong>Molfetta<\/strong>, invece, la suggestiva processione notturna richiama numerosi visitatori ogni anno.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Nel periodo pasquale, i <strong>mercati locali<\/strong> si animano di colori e profumi, offrendo prodotti artigianali e specialit\u00e0 tipiche. Tra queste spicca la cuddura cull\u2019ova, un dolce tradizionale a forma di ciambella decorato con uova sode, simbolo di rinascita, insieme a tante altre delizie della tradizione.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>La <strong>printemps<\/strong>, inoltre, \u00e8 la stagione perfetta per scoprire le bellezze naturali della regione. Il <strong>Parc national du Gargano<\/strong> et le\u00a0<strong>Parc national de l'Alta Murgia<\/strong>\u00a0regalano panorami spettacolari e percorsi ideali per escursioni a piedi o in bicicletta, permettendo di immergersi in una natura rigogliosa e ancora autentica. Esplorare questi luoghi significa vivere un\u2019esperienza completa, tra cultura, tradizione e paesaggi indimenticabili.<\/p>\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\n<p>Se quindi hai voglia di trascorrere la Pasqua in Puglia non perderti le tante esperienze e attivit\u00e0 turistiche messe a disposizione da <strong>Movery <\/strong>per rilassarsi tra le meraviglie di una delle regioni pi\u00f9 belle d\u2019Italia!<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading -->\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Le_migliori_esperienze_da_fare_in_Puglia_a_Pasqua\"><\/span>Le migliori esperienze da fare in Puglia a Pasqua<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Laboratori_di_cucina_e_cooking_class_in_provincia_di_Brindisi\"><\/span><strong>Laboratori di cucina e cooking class in provincia di Brindisi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Una delle destinazioni pi\u00f9 amate in Puglia \u00e8<strong> <a href=\"https:\/\/movery.it\/fr\/esplora\/destinazioni\/puglia\/brindisi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brindisi<\/a> <\/strong>che nel corso dei secoli \u00e8 stata punto strategico per i collegamenti tra l\u2019Italia e l\u2019Oriente. Gi\u00e0 in epoca romana, infatti, Brindisi rappresentava il punto di arrivo della <strong>Via Appia<\/strong>, una delle strade pi\u00f9 importanti dell\u2019Impero, da cui partivano navi dirette verso la Grecia e altre regioni del Mediterraneo. Nel corso dei secoli, la citt\u00e0 \u00e8 passata sotto il dominio di diversi popoli, tra cui Bizantini, Normanni e Svevi, e ognuno di loro ha lasciato tracce visibili ancora oggi nell\u2019architettura e nella cultura locale. Passeggiando per Brindisi si possono ammirare monumenti significativi come le<strong> Colonne Romane di Brindisi<\/strong>, che segnano simbolicamente la fine della Via Appia, oppure il <strong>Castello Svevo di Brindisi<\/strong>, costruito per volere di Federico II e il Castello Alfonsino. Se invece vuoi divertirti nei dintorni della citt\u00e0 pugliese puoi scegliere una <strong><a href=\"https:\/\/movery.it\/fr\/puglia\/brindisi\/lezione-di-pizzica-e-taranta-in-puglia-con-degustazione\/\" target=\"_blank\" rel=\"noreferrer noopener\">lezione di pizzica e taranta con assaggio di prodotti tipici<\/a><\/strong> ou<strong> <a href=\"https:\/\/movery.it\/fr\/puglia\/brindisi\/cooking-class-per-imparare-a-fare-le-orecchiette\/\" target=\"_blank\" rel=\"noreferrer noopener\">cooking class sulle orecchiette con aperitivo e pranzo<\/a><\/strong>, entrambe a Ceglie Messapica.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Escursione_a_piedi_nel_cuore_di_Taranto\"><\/span><strong>Escursione a piedi nel cuore di Taranto<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<!-- \/wp:heading --><!-- wp:paragraph -->\n<p>Altra attivit\u00e0 imperdibile in Puglia \u00e8il <strong><a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\" target=\"_blank\" rel=\"noreferrer noopener\">Visite \u00e0 pied de Tarente<\/a><\/strong>. Accompagnato da una guida turistica esperta e grazie all\u2019ausilio di video, immagini e testimonianze, avrai l\u2019opportunit\u00e0 di scoprire alcuni dei luoghi pi\u00f9 significativi della citt\u00e0. Potrai ammirare il suggestivo <strong>Pont tournant<\/strong>, i resti romani di Piazza Garibaldi e il lungomare Vittorio Emanuele III. Il percorso proseguir\u00e0 tra importanti punti di interesse, come la <strong>Chiesa del Carmine<\/strong>, il Monumento ai Caduti di Guerra e il <strong>Monumento ai Marinari<\/strong>, fino a raggiungere il Ponte Punta Penna Pizzone, la <strong>Concattedrale <\/strong>e le pi\u00f9 affascinanti opere contemporanee del Complesso Beni Stabili.<\/p>\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><!-- \/wp:paragraph -->\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-538ebcc e-flex e-con-boxed e-con e-parent\" data-id=\"538ebcc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6927112 elementor-widget elementor-widget-shortcode\" data-id=\"6927112\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    \n    <div class=\"st-relate st-hotel-room-content\">\n        <div class=\"relate-rooms\">\n            <div class=\"st-hr\"><\/div>\n            <h2 class=\"st-heading-section\"><span class=\"ez-toc-section\" id=\"Proposition_for_you\"><\/span>Proposition pour vous<span class=\"ez-toc-section-end\"><\/span><\/h2>\n            <div class=\"inner service-list-wrapper service-tour\">\n                <div class=\"owl-carousel st-owl-slider\" data-loop=\"false\" data-center=\"true\" data-margin=\"24\" data-responsive=\"{&quot;992&quot;:{&quot;items&quot;:4},&quot;768&quot;:{&quot;items&quot;:2},&quot;0&quot;:{&quot;items&quot;:1}}\"><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n        <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n            <div class=\"title\">\n                Excursion            <\/div>\n            <div class=\"icon\">\n\n                                    <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n\n                        <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n                            <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                            <div class=\"lds-dual-ring\"><\/div>\n                        <\/div>\n                    <\/a>\n                                <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/tour-in-barca-tra-i-delfini-a-taranto-con-aperitivo-a-bordo\/\">\n                    <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n                <\/a>\n                <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/tour-in-barca-tra-i-delfini-a-taranto-con-aperitivo-a-bordo\/\">\n                    <img decoding=\"async\" src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n                <\/a>\n\n            <\/div>\n\n        <\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                                                \n            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/tour-in-barca-tra-i-delfini-a-taranto-con-aperitivo-a-bordo\/\">\n                <img decoding=\"async\" class=\"feature_activity_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2026\/02\/delfini_taranto_tour_barca-scaled-450x300.jpg\" alt=\"Excursion en bateau pour les dauphins \u00e0 Tarente avec ap\u00e9ritif \u00e0 bord\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/tour-in-barca-tra-i-delfini-a-taranto-con-aperitivo-a-bordo\/\" class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n                <p class=\"title\" itemprop=\"name\">\n                    Excursion en bateau pour les dauphins \u00e0 Tarente avec ap\u00e9ritif \u00e0 bord                <\/p>\n            <\/a>\n            \n\n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Canal Harbour de Marina Ginosa<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n                Envie d'une journ\u00e9e de d\u00e9tente et de paix ? R\u00e9servez cette excursion en bateau \u00e0...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t3.5 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tTr\u00e8s bon\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (5 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n\n                        <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\" >\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac55.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n\n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/tour-in-barca-tra-i-delfini-a-taranto-con-aperitivo-a-bordo\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n        <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n            <div class=\"title\">\n                Exp\u00e9riences            <\/div>\n            <div class=\"icon\">\n\n                                    <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n\n                        <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n                            <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                            <div class=\"lds-dual-ring\"><\/div>\n                        <\/div>\n                    <\/a>\n                                <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/escursione-a-cavallo-nel-cuore-della-puglia\/\">\n                    <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n                <\/a>\n                <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/escursione-a-cavallo-nel-cuore-della-puglia\/\">\n                    <img decoding=\"async\" src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n                <\/a>\n\n            <\/div>\n\n        <\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                                                \n            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/escursione-a-cavallo-nel-cuore-della-puglia\/\">\n                <img decoding=\"async\" class=\"feature_activity_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2025\/10\/passeggiata_cavallo_ostuni_mare-450x300.jpg\" alt=\"Randonn\u00e9e \u00e0 cheval \u00e0 Ostuni, au c\u0153ur des Pouilles\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/escursione-a-cavallo-nel-cuore-della-puglia\/\" class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n                <p class=\"title\" itemprop=\"name\">\n                    Randonn\u00e9e \u00e0 cheval \u00e0 Ostuni, au c\u0153ur des Pouilles                <\/p>\n            <\/a>\n            \n\n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Ostuni<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n                Pour passer un bon moment entre amis et en famille, rien de tel qu'une belle balade \u00e0 travers...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t3.8 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tTr\u00e8s bon\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (4 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n\n                        <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\" >\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac110.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n\n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/escursione-a-cavallo-nel-cuore-della-puglia\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n    <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n<div class=\"title\" >\n    Visites \u00e0 pied<\/div>\n<div class=\"icon\">\n\n        <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n        \n            <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n            <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                <div class=\"lds-dual-ring\"><\/div>\n            <\/div>\n        <\/a>\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n    <\/a>\n    <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n    <\/a>\n    \n<\/div>\n\n<\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                \n                                                            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\">\n                <img decoding=\"async\" class=\"feature_tour_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2025\/10\/private-tour-of-the-withe-city-of-ostuni2-450x300.png\"\n                     alt=\"Visite priv\u00e9e du centre historique d&#039;Ostuni\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\"  class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n        <p class=\"title\" itemprop=\"name\">\n               Visite priv\u00e9e du centre historique d'Ostuni        <\/p>\n                <\/a>   \n        \n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Via Antonio Specchia, 43 \u00e0 Ostuni<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n            Vous voulez en savoir plus sur la ville d'Ostuni ? Ne manquez pas cette visite priv\u00e9e...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t3.8 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tTr\u00e8s bon\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (4 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n            \n                     <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\">\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac60.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n                    \n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n        <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n            <div class=\"title\">\n                Cours de cuisine            <\/div>\n            <div class=\"icon\">\n\n                                    <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n\n                        <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n                            <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                            <div class=\"lds-dual-ring\"><\/div>\n                        <\/div>\n                    <\/a>\n                                <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/lezione-di-cucina-pugliese-orecchiette-aperitivo-e-vino-a-polignano\/\">\n                    <img decoding=\"async\" src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n                <\/a>\n                <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/lezione-di-cucina-pugliese-orecchiette-aperitivo-e-vino-a-polignano\/\">\n                    <img decoding=\"async\" src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n                <\/a>\n\n            <\/div>\n\n        <\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                                                \n            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/lezione-di-cucina-pugliese-orecchiette-aperitivo-e-vino-a-polignano\/\">\n                <img decoding=\"async\" class=\"feature_activity_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2025\/10\/cooking_pasta_polignano-450x300.jpg\" alt=\"Cours de cuisine typique des Pouilles : Orecchiette, ap\u00e9ritif et vin \u00e0 Polignano a Mare\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/lezione-di-cucina-pugliese-orecchiette-aperitivo-e-vino-a-polignano\/\" class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n                <p class=\"title\" itemprop=\"name\">\n                    Cours de cuisine typique des Pouilles : Orecchiette, ap\u00e9ritif et vin \u00e0 Polignano a Mare                <\/p>\n            <\/a>\n            \n\n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Via san vito 20, Polignano a Mare<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n                Participez \u00e0 un cours de cuisine typique des Pouilles \u00e0 Polignano a Mare : apprenez \u00e0 pr\u00e9parer...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t4.5 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (5 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n\n                        <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\" >\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac35.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n\n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/lezione-di-cucina-pugliese-orecchiette-aperitivo-e-vino-a-polignano\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n    <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n<div class=\"title\" >\n    Visites \u00e0 pied<\/div>\n<div class=\"icon\">\n\n        <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n        \n            <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n            <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n\n                <div class=\"lds-dual-ring\"><\/div>\n            <\/div>\n        <\/a>\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n\n    <\/a>\n    <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\" \/>\n    <\/a>\n    \n<\/div>\n\n<\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                \n                                                            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\">\n                <img decoding=\"async\" class=\"feature_tour_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2025\/10\/esperienza_matera_da_bari-450x300.png\"\n                     alt=\"Excursion priv\u00e9e \u00e0 Matera au d\u00e9part de Bari\" \/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\"  class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n        <p class=\"title\" itemprop=\"name\">\n               Excursion priv\u00e9e \u00e0 Matera au d\u00e9part de Bari        <\/p>\n                <\/a>   \n        \n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Bari<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t5h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n            Circuit dans la belle Matera avec d\u00e9part de Bari pour admirer ses sassi caract\u00e9ristiques et...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t4.2 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (6 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n            \n                     <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\">\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac55.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n                    \n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n    <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n<div class=\"title\" >\n    Cours de cuisine<\/div>\n<div class=\"icon\">\n\n        <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n        \n            <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n            <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n\n                <div class=\"lds-dual-ring\"><\/div>\n            <\/div>\n        <\/a>\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/corso-di-cucina-con-degustazione-di-panzerotti-focacce-e-orecchiette\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n    <\/a>\n    <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/corso-di-cucina-con-degustazione-di-panzerotti-focacce-e-orecchiette\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n    <\/a>\n    \n<\/div>\n\n<\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                \n                                                            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/corso-di-cucina-con-degustazione-di-panzerotti-focacce-e-orecchiette\/\">\n                <img decoding=\"async\" class=\"feature_tour_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2024\/11\/Cooking_class_preparaizione-450x300.jpg\"\n                     alt=\"Cours de cuisine \u00e0 Polignano a Mare avec d\u00e9gustation de panzerotti, focaccia et orecchiette\"\/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/corso-di-cucina-con-degustazione-di-panzerotti-focacce-e-orecchiette\/\"  class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n        <p class=\"title\" itemprop=\"name\">\n               Cours de cuisine \u00e0 Polignano a Mare avec d\u00e9gustation de panzerotti, focaccia et orecchiette        <\/p>\n                <\/a>   \n        \n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Piazza Caduti di Via Fani, Polignano a Mare<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t4h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n            Vous cherchez une exp\u00e9rience amusante et \u00e9ducative ? Avec ce cours de cuisine avec d\u00e9gustation \u00e0 Polignano a...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t4.8 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (3 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n            \n                     <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\">\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac175.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n                    \n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/corso-di-cucina-con-degustazione-di-panzerotti-focacce-e-orecchiette\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n    <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n<div class=\"title\" >\n    Visites \u00e0 pied<\/div>\n<div class=\"icon\">\n\n        <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n        \n            <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n            <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n\n                <div class=\"lds-dual-ring\"><\/div>\n            <\/div>\n        <\/a>\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n    <\/a>\n    <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n    <\/a>\n    \n<\/div>\n\n<\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                \n                                                            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\">\n                <img decoding=\"async\" class=\"feature_tour_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2024\/11\/mozarella_ostuni_tour-450x300.png\"\n                     alt=\"Visite de la Mozzarella \u00e0 Ostuni avec d\u00e9gustation de produits locaux\"\/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\"  class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n        <p class=\"title\" itemprop=\"name\">\n               Visite de la Mozzarella \u00e0 Ostuni avec d\u00e9gustation de produits locaux        <\/p>\n                <\/a>   \n        \n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Via Ceglie, 102, 72013 Ostuni<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t1h 30min \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n            Vous souhaitez passer une journ\u00e9e agr\u00e9able dans un endroit sp\u00e9cial ? Choisissez cette excursion \u00e0 la mozzarella...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t3.2 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tTr\u00e8s bon\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (4 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n            \n                     <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\">\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac25.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n                    \n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><div class=\"item-slide\"><div class=\"services-item grid item-elementor mb-3\" itemscope itemtype=\"https:\/\/schema.org\/Trip\">\n    <div class=\"item service-border st-border-radius\">\n    <div class=\"header-services-item\" style=\"height: 50px; backround:black\">\n\n<div class=\"title\" >\n    Visites \u00e0 pied<\/div>\n<div class=\"icon\">\n\n        <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\n        \n            <div class=\"service-add-wishlist\" title=\"Ajouter \u00e0 la liste de souhaits\">\n            <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/ico-favgreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n\n                <div class=\"lds-dual-ring\"><\/div>\n            <\/div>\n        <\/a>\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/movery.it\/assets\/icons\/card-shopping-cart.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n\n    <\/a>\n    <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\">\n    <img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/static.movery.it\/assets\/img\/icons\/ico-sharegreen.svg\" height=\"15\" width=\"15\" class=\"movery-home-main-items-child-pic-share ignore-mouse-events\" alt=\"Partager\">\n    <\/a>\n    \n<\/div>\n\n<\/div>\n        <div class=\"featured-image\">\n            <div class=\"st-tag-feature-sale\">\n                \n                                                            <\/div>\n\n            <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\">\n                <img decoding=\"async\" class=\"feature_tour_img\" itemprop=\"photo\" src=\"https:\/\/movery.it\/wp-content\/uploads\/2024\/11\/tour_taranto_esperienza_privata-450x300.png\"\n                     alt=\"Visite \u00e0 pied \u00e0 Tarente : d\u00e9couverte de la ville immortelle\"\/>\n            <\/a>\n                    <\/div>\n        <div class=\"content-item\">\n        <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\"  class=\"title-a\" style=\"height: 3rem;overflow: hidden;\">\n        <p class=\"title\" itemprop=\"name\">\n               Visite \u00e0 pied \u00e0 Tarente : d\u00e9couverte de la ville immortelle        <\/p>\n                <\/a>   \n        \n                            <div class=\"sub-title st-address d-flex\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\n                    <span class=\"address\" itemprop=\"address\" itemscope itemtype=\"https:\/\/schema.org\/PostalAddress\">\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Place du ch\u00e2teau<\/span>\n                    <\/span>\n\t\t\t\t\t                            <span class=\"duration\">\n\t\t\t\t\t\t\t\t<i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"11px\" width=\"11px\" version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewbox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#013451\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>\t\t\t\t\t\t\t\t2h  \n                        <\/span>\n                                        <\/div>\n            \n            <div class=\"excerpt\" style=\"height: 3rem;\">\n            Vous \u00eates \u00e0 la recherche d'une exp\u00e9rience particuli\u00e8re ? Alors achetez cette visite priv\u00e9e d\u00e8s maintenant...            <\/div>\n\n\n            <div class=\"reviews\" itemprop=\"starRating\" itemscope itemtype=\"https:\/\/schema.org\/Rating\"  style=\"display: block;padding-left: 15px;margin-top: 15px; height: 48px;\">\n                <i class=\"stt-icon-star1\"><\/i>\n                <span class=\"rate\" itemprop=\"ratingValue\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\t4.8 <span>\/<\/span> 5\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"rate-text\" style=\"color: #0f3f5b;\">\n\t\t\t\t\t\tExcellent\t\t\t\t\t<\/span>\n                <span class=\"summary\">\n                    (2 commentaires)\n                <\/span>\n            <\/div>\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 01:31:49\">2026-09-02 01:31:49<\/div>\n            \n                     <div class=\"section-footer\">\n                                <div class=\"section_footer_content\" itemprop=\"priceRange\">\n                    <span class=\"price-tour\">\n                        <span class=\"price\">&nbsp;&nbsp;&nbsp;&nbsp;<span class=\"sale-top\">De  <span class=\"text-lg lh1em item\"> \u20ac42.00<\/span><\/span><br>&nbsp;&nbsp;&nbsp;&nbsp;une personne<\/span>\n                    <\/span>\n                    \n                                                <span class=\"unit\">\n\t\t\t\t\t\t        <a href=\"https:\/\/movery.it\/fr\/puglia\/taranto\/walking-tour-a-taranto-scopri-la-citta-immortale\/\" class=\"add_tour\">\n\t\t\t\t\t\t\t        Livre \n\t\t\t\t\t\t        <\/a>\n                            <\/span>\n                                        <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><\/div>            <\/div>\n        <\/div>\n    <\/div>\n    \n    \t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b75a7d elementor-widget elementor-widget-text-editor\" data-id=\"2b75a7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Mozzarella_tour_a_Ostuni_con_degustazione_di_prodotti_locali\"><\/span><strong>Visite de la Mozzarella \u00e0 Ostuni avec d\u00e9gustation de produits locaux<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>I pi\u00f9 golosi possono prenotare una <strong><a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/mozzarella-tour-con-degustazione-di-prodotti-locali\/\" target=\"_blank\" rel=\"noreferrer noopener\">masterclass dedicata alla mozzarella a Ostuni con assaggio di prodotti locali<\/a><\/strong>. L\u2019esperienza si svolge all\u2019interno di una tipica masseria pugliese e ha inizio con l\u2019incontro con un mastro casaro che guider\u00e0 un coinvolgente workshop dedicato alla produzione della vera <strong>mozzarella di Puglia<\/strong>. Durante la visita potrai esplorare le stalle, dove vivono maiali, vitelli e mucche. Non mancheranno una tappa nell\u2019orto biologico della masseria e uno sguardo alla sala della mungitura.Il percorso prosegue nel caseificio, dove assisterai alle diverse fasi di lavorazione di specialit\u00e0 come <strong>mozzarella<\/strong>, <strong>burrata<\/strong>, <strong>stracciatella <\/strong>e altri formaggi tipici pugliesi. A conclusione dell\u2019esperienza, ti aspetta una gustosa <strong>d\u00e9gustation <\/strong>con un\u2019ampia selezione di prodotti locali come salumi e prodotti da forno, burratine, mozzarelle, capocollo, salame, focacce al pomodoro e molte altre delizie della tradizione.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wine_tour_a_Monopoli_con_degustazione_di_prodotti_pugliesi\"><\/span><strong>Wine tour a Monopoli con degustazione di prodotti pugliesi<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Chi invece \u00e8 appassionato di prodotti vinicoli pu\u00f2 preferire un<strong> <a href=\"https:\/\/movery.it\/fr\/puglia\/monopoli\/wine-tour-a-monopoli-con-degustazione-di-prodotti-locali\/\" target=\"_blank\" rel=\"noreferrer noopener\">tour del vino a Monopoli<\/a><\/strong>. L\u2019attivit\u00e0 ti attende in un accogliente agriturismo pugliese e inizia con un breve momento di benvenuto, seguito da un\u2019immersione nella<strong> culture \u0153nologique <\/strong>del territorio. Durante il tour avrai l\u2019opportunit\u00e0 di degustare una selezione curata di vini, accompagnata da un <strong>tipico pranzo pugliese <\/strong>composto da antipasto della casa, una portata principale, dessert e acqua. Il wine tasting prevede in particolare l\u2019<strong>assaggio guidato <\/strong>di tre calici: un vino bianco, un rosato e un rosso, scelti per rappresentare al meglio le caratteristiche locali. Questa esperienza ti permetter\u00e0 di vivere appieno l\u2019atmosfera autentica dell\u2019agriturismo, lasciandoti conquistare da sapori genuini e raffinati che raccontano la tradizione pugliese.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Corso_di_cucina_a_Polignano_a_Mare_con_degustazione_di_panzerotti_focacce_e_orecchiette\"><\/span><strong>Cours de cuisine \u00e0 Polignano a Mare avec d\u00e9gustation de panzerotti, focaccia et orecchiette<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Vuoi sapere proprio tutti sulla cucina pugliese? A Pasqua non lasciarti scappare questo divertente <a href=\"https:\/\/movery.it\/fr\/puglia\/brindisi\/cooking-class-per-imparare-a-fare-le-orecchiette\/\" target=\"_blank\" rel=\"noreferrer noopener\">l<\/a><strong><a href=\"https:\/\/movery.it\/fr\/puglia\/brindisi\/cooking-class-per-imparare-a-fare-le-orecchiette\/\" target=\"_blank\" rel=\"noreferrer noopener\">aboratorio di cucina a Polignano a Mare con assaggio di piatti tipici<\/a><\/strong>. In compagnia di due maestre esperte avrai l\u2019opportunit\u00e0 di cimentarti nella preparazione di due sughi, scelti in base alla stagionalit\u00e0 degli ingredienti. Agli allievi verr\u00e0 insegnato a preparare l\u2019<strong>impasto base delle orecchiette<\/strong> e di altri quattro formati di pasta tipici pugliesi, che verranno poi cucinati insieme. Terminata questa fase, ti sar\u00e0 offerto un <strong>ap\u00e9ritif <\/strong>a base di frisa, accompagnata da vino locale e il <strong>d\u00e9jeuner <\/strong>che prevede un men\u00f9 composto da un antipasto di verdure di stagione, due primi piatti e un secondo. A concludere, non mancheranno il dolce, con bocconcini di marmellata o tarallini glassati, e la frutta fresca.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Street_food_tour_a_Polignano_a_Mare_con_degustazione\"><\/span><strong>Visite guid\u00e9e de la cuisine de rue \u00e0 Polignano a Mare avec d\u00e9gustation<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Il est \u00e9galement tr\u00e8s int\u00e9ressant de noter que la<strong><a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/street-food-tour-con-degustazione\/\" target=\"_blank\" rel=\"noreferrer noopener\">escursione sullo street food a Polignano a Mare con degustazione<\/a><\/strong>. La prima tappa dell\u2019escursione sar\u00e0 dedicata alla degustazione del celebre<strong> Caff\u00e8 Speciale di Polignano a Mare<\/strong>, una variante unica della bevanda nata proprio in citt\u00e0, preparata con caff\u00e8, zucchero, panna, amaretto e scorza di limone. Successivamente, \u00e8 prevista una sosta per assaporare la tradizionale <strong>Focaccia des Pouilles<\/strong>, seguita da un\u2019altra degustazione dedicata al classico <strong>panzerotto<\/strong>, proposto in diverse varianti. L\u2019esperienza gastronomica continuer\u00e0 con un calice di vino locale, accompagnato da prodotti tipici come <strong>burrata <\/strong>et <strong>capocollo di Martina Franca<\/strong>. Il tour proseguir\u00e0 poi con una piacevole passeggiata tra i suggestivi vicoli del centro storico di Polignano a Mare, durante la quale ci saranno varie soste per scattare fotografie nei punti pi\u00f9 caratteristici.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tour_privato_a_Polignano_Alberobello_e_Locorotondo_in_partenza_da_Matera\"><\/span><strong>Excursion priv\u00e9e \u00e0 Polignano, Alberobello et Locorotondo au d\u00e9part de Matera<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Se invece vuoi muoverti tra diverse localit\u00e0 della Puglia ti suggeriamo il<strong> <a href=\"https:\/\/movery.it\/fr\/puglia\/polignano-a-mare\/tour-privato-a-polignano-alberobello-e-locorotondo-da-matera\/\" target=\"_blank\" rel=\"noreferrer noopener\">tour tra Polignano a Mare, Alberobello e Locorotondo<\/a><\/strong> che prende il via da Matera. L\u2019escursione prende il via dal suggestivo borgo di Polignano a Mare che regala panorami spettacolari e scorci indimenticabili. Il viaggio prosegue verso <strong>Alberobello<\/strong>, la celebre citt\u00e0 dei trulli, dove potrai passeggiare tra queste caratteristiche costruzioni nei quartieri di <strong>Petite Haye <\/strong>et <strong>Quartier Monti<\/strong>. Qui avrai modo di ammirare luoghi iconici come il Trullo Siamese, la Chiesa di Sant\u2019Antonio, il Museo del Territorio e la Casa d\u2019Amore. La tappa successiva \u00e8 <strong>Locorotondo<\/strong>, uno dei borghi pi\u00f9 belli d\u2019Italia, dove potrai visitare la Chiesa Madre di San Giorgio, la Villa Comunale, la Torre Civica e il Palazzo Morelli, oltre a lasciarti incantare dai vicoli fioriti e dall\u2019atmosfera autentica del borgo.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Walking_tour_privato_a_Matera_in_partenza_da_Bari\"><\/span><strong>Excursion priv\u00e9e \u00e0 Matera au d\u00e9part de Bari<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Hai voglia di esplorare la citt\u00e0 dei Sassi? Prenota subito questo <strong><a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/walking-tour-privato-a-matera-in-partenza-da-bari\/\" target=\"_blank\" rel=\"noreferrer noopener\">tour a piedi a Matera in partenza da Bari<\/a><\/strong>. Avrai la possibilit\u00e0 di vivere un\u2019escursione di un\u2019intera giornata con un comodo <strong>transfert <\/strong>a tua disposizione. Viaggerai a bordo di un<strong> minivan privato<\/strong>, cos\u00ec da goderti un\u2019esperienza confortevole, rilassante e personalizzata, senza doverti preoccupare dei mezzi pubblici o della ricerca del parcheggio. Una volta arrivato a Matera, potrai approfondire la conoscenza della citt\u00e0 partecipando a una visita guidata dei celebri<strong> Sassi di Matera<\/strong>. La guida ti accompagner\u00e0 alla scoperta di queste affascinanti abitazioni scavate nella roccia, raccontandoti la loro storia e curiosi aneddoti legati alla loro costruzione e al loro utilizzo nel tempo. La visita guidata \u00e8 facoltativa: chi lo desidera potr\u00e0 infatti scegliere di esplorare Matera in autonomia, passeggiando tra i suoi vicoli e scoprendone le meraviglie secondo i propri ritmi.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tour_privato_nel_centro_storico_di_Ostuni\"><\/span><strong>Visite priv\u00e9e du centre historique d'Ostuni<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Se adori il Salento e le sue bellezze ti proponiamo un\u2019<strong><a href=\"https:\/\/movery.it\/fr\/puglia\/ostuni\/tour-privato-nel-centro-storico-di-ostuni\/\" target=\"_blank\" rel=\"noreferrer noopener\">escursione nel centro storico di Ostuni<\/a><\/strong>. Parteciperai a un tour privato di Ostuni che ti porter\u00e0 alla scoperta della sua storia secolare, immergendoti nell\u2019atmosfera unica del suo centro storico. Passeggerai tra un intricato intreccio di vicoli, stradine e scorci panoramici, lasciandoti affascinare dal carattere autentico della citt\u00e0. In particolare, percorrerai<strong> Via Cattedrale<\/strong> e, insieme alla tua guida, potrai ammirare gli edifici storici della zona, le antiche mura e la splendida <strong>Cath\u00e9drale Sainte-Marie-de-l'Assomption<\/strong>, straordinario esempio di architettura gotica.Il tour proseguir\u00e0 con la visita di Piazza della Libert\u00e0, dove si trovano la <strong>Colonne de Sant'Oronzo<\/strong> et le <strong>Chiesa di San Francesco d\u2019Assisi<\/strong>, completando cos\u00ec un percorso ricco di storia, arte e panorami indimenticabili.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tour_privato_a_Bari_Gravina_Castel_del_Monte_e_Trani_in_partenza_da_Matera\"><\/span><strong>Tour privato a Bari, Gravina, Castel del Monte e Trani in partenza da Matera<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Movery per te a Pasqua ha pensato anche ad un<strong> <a href=\"https:\/\/movery.it\/fr\/puglia\/bari\/tour-a-gravina-e-trani-in-partenza-da-matera-o-da-bari\/\" target=\"_blank\" rel=\"noreferrer noopener\">tour tra Bari, Gravina, Castel del Monte e Trani<\/a> <\/strong>che parte da Matera. Qui un autista ti attender\u00e0 per accompagnarti verso Bari. Una volta arrivato nel capoluogo pugliese, potrai esplorare alcuni dei suoi luoghi pi\u00f9 iconici, come la <strong>Basilique Saint-Nicolas<\/strong>les <strong>Ch\u00e2teau normand-swabien <\/strong>e le pittoresche stradine di <strong>Bari Vecchia<\/strong>. A seguire, ti sposterai a Gravina in Puglia, dove potrai ammirare il suggestivo <strong>Ponte Acquedotto di Gravina<\/strong> e la Cattedrale di Santa Maria Assunta. Il viaggio proseguir\u00e0 poi verso lo straordinario <strong>Castel del Monte<\/strong>, celebre maniero ottagonale del XIII secolo voluto da Federico II di Svevia, che potrai ammirare per la sua architettura unica e affascinante. Per concludere, raggiungerai <strong>Trani<\/strong>, elegante citt\u00e0 affacciata sul mare, dove visiterai la Cattedrale di San Nicola Pellegrino e il Castello Svevo di Trani. Al termine del tour, farai rientro a Matera.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} --><\/p>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Tour_guidato_tra_i_trulli_e_le_meraviglie_di_Alberobello\"><\/span><strong>Visite guid\u00e9e des trulli et des merveilles d'Alberobello<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Per finire, ti proponiamo un\u2019<strong><a href=\"https:\/\/movery.it\/fr\/puglia\/alberobello\/tour-guidato-tra-i-trulli\/\" target=\"_blank\" rel=\"noreferrer noopener\">escursione guidata tra i trulli di Alberobello<\/a><\/strong>. Il punto di ritrovo per il tour \u00e8 fissato davanti al Trullo Sovrano, in Piazza Sacramento. Da qui prender\u00e0 il via un affascinante percorso alla scoperta di Alberobello, con una prima tappa presso la <strong>Basilique des saints Cosmas et Damien<\/strong>. Il tour proseguir\u00e0 nel suggestivo Quartiere Neoclassico, caratterizzato da stradine acciottolate, cortili nascosti e palazzi raffinati. L\u2019itinerario include anche una sosta alla<strong> Casa D'Amore<\/strong>, edificio storico del XVIII secolo, simbolo della storia e dell\u2019identit\u00e0 del borgo. Dalla Terrazza panoramica di Santa Lucia potrai godere di una vista mozzafiato sull\u2019intera citt\u00e0. Raggiungerai poi il celebre <strong>Quartier Monti<\/strong>, la zona monumentale che ospita oltre mille trulli e rappresenta uno degli scorci pi\u00f9 caratteristici del territorio.Quindi visiterai l\u2019interno della <strong>\u00c9glise de Saint-Antoine<\/strong>, nota anche come \u201cChiesa Trullo\u201d, per poi proseguire verso il<strong> Quartier de la Petite Haye<\/strong>.Durante il tour sar\u00e0 previsto anche del tempo libero, ideale per esplorare i trulli trasformati in botteghe artigiane, bar, negozi di souvenir e ristoranti tipici.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La Pasqua in Puglia \u00e8 una celebrazione profondamente radicata nelle tradizioni e nella cultura secolare&#8230;<\/p>","protected":false},"author":10,"featured_media":33512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Esperienze e attivit\u00e0 turistiche da fare in Puglia per trascorrere in allegria i giorni di Pasqua","_seopress_titles_desc":"Ti piacerebbe passare la Pasqua in Puglia? Con Movery avrai a disposizione moltissimi tour ed esperienze a tema per conoscere meglio la cultura e la cucina locale","_seopress_robots_index":"","content-type":"","footnotes":""},"categories":[319],"tags":[],"locations":[812,816,778,781,780,805,782,813,779,808,811,843,804,810,807,802,325,814,783,806],"class_list":["post-58373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","locations-alberobello","locations-altamura","locations-bari","locations-barletta-andria-trani","locations-brindisi","locations-fasano","locations-foggia","locations-gargano","locations-lecce","locations-manfredonia","locations-monopoli","locations-nardo","locations-ostuni-2","locations-otranto-puglia","locations-peschici","locations-polignano-a-mare","locations-puglia","locations-salento","locations-taranto","locations-vieste"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","_links":{"self":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/58373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/comments?post=58373"}],"version-history":[{"count":5,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/58373\/revisions"}],"predecessor-version":[{"id":58603,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/posts\/58373\/revisions\/58603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/media\/33512"}],"wp:attachment":[{"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/media?parent=58373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/categories?post=58373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/tags?post=58373"},{"taxonomy":"locations","embeddable":true,"href":"https:\/\/movery.it\/fr\/wp-json\/wp\/v2\/locations?post=58373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}